{"id":288,"date":"2024-09-23T22:14:00","date_gmt":"2024-09-23T22:14:00","guid":{"rendered":"https:\/\/riet-edu.org\/2025\/?p=288"},"modified":"2025-10-22T17:17:03","modified_gmt":"2025-10-22T17:17:03","slug":"participamos-de-la-campana-volver-a-estudiar-2024","status":"publish","type":"post","link":"https:\/\/riet-edu.org\/2025\/participamos-de-la-campana-volver-a-estudiar-2024\/","title":{"rendered":"Participamos de la campa\u00f1a \u201cVolver a Estudiar\u201d 2024"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; custom_padding_last_edited=\u00bbon|phone\u00bb admin_label=\u00bbHeader\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb11ba69ed-1fc1-4cbf-aa7a-5a8f430d68b2&#8243; background_enable_color=\u00bboff\u00bb background_image=\u00bbhttps:\/\/riet-edu.org\/2025\/wp-content\/uploads\/2025\/10\/fondo-home.jpg\u00bb parallax=\u00bbon\u00bb custom_padding=\u00bb8vw||0px||false|false\u00bb custom_padding_tablet=\u00bb12vw||0px||false|false\u00bb custom_padding_phone=\u00bb20vw||0px||false|false\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bb2e876a24-7bcb-47af-ae47-8f4b38b8cbbd\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_title author=\u00bboff\u00bb date_format=\u00bbj %92d%92e F %92d%92e Y\u00bb categories=\u00bboff\u00bb comments=\u00bboff\u00bb featured_image=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bb#FFFFFF\u00bb meta_font=\u00bb|700|||||||\u00bb meta_text_align=\u00bbcenter\u00bb meta_text_color=\u00bb#FFFFFF\u00bb meta_font_size=\u00bb16px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_post_title][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; admin_label=\u00bbListings\u00bb module_id=\u00bbFormacion-y-Webinars\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bb_initial\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.25.2&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_post_title title=\u00bboff\u00bb meta=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_post_title][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font=\u00bb|700|||||||\u00bb text_text_color=\u00bb#1295AF\u00bb text_font_size=\u00bb18px\u00bb custom_padding=\u00bb||30px||false|false\u00bb border_width_bottom=\u00bb1px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<div class=\"contenido_individual_noticia pl0\">La campa\u00f1a \u00abVolver a estudiar\u00bb tiene por objetivo promover la terminalidad de la educaci\u00f3n secundaria entre adolescentes, j\u00f3venes y personas adultas involucrando a la sociedad y a referentes del mundo del deporte.<\/div>\n<p>[\/et_pb_text][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>Comprometidos con la educaci\u00f3n en todos sus niveles y modalidades la RIET es parte de la edici\u00f3n de la campa\u00f1a <a href=\"https:\/\/oei.int\/oficinas\/argentina\/volveraestudiar\/sobre-la-campana\" target=\"_blank\" rel=\"noopener\">\u201cVolver a Estudiar\u201d 2024,<\/a> una iniciativa conjunta del Comit\u00e9 Ol\u00edmpico Argentino (COA) y la Organizaci\u00f3n de Estados Iberoamericanos para la Educaci\u00f3n, la Ciencia y la Cultura (OEI) en Argentina.<\/p>\n<p>Inspirados por los antecedentes de las ediciones 2022 y 2023 y por la celebraci\u00f3n de los Juegos Ol\u00edmpicos de Par\u00eds 2024, COA y OEI realizaron una nueva campa\u00f1a con el protagonismo de atletas argentinos\/as consagrados\/as como Paula Pareto, doble medallista ol\u00edmpica y campeona del mundo en judo; Leandro Usuna, primer surfista ol\u00edmpico argentino y campe\u00f3n del mundo en surf; Walter P\u00e9rez, medallista ol\u00edmpico y campe\u00f3n del mundo en ciclismo; Cecilia Carranza, campeona ol\u00edmpica y subcampeona del mundo en vela; Delfina Merino, doble medallista ol\u00edmpica y campeona del mundo en hockey sobre c\u00e9sped; y Silvio Velo, doble medallista paral\u00edmpico y campe\u00f3n mundial en f\u00fatbol.<\/p>\n<p>La finalidad de la iniciativa es lograr la reinserci\u00f3n de adolescentes, j\u00f3venes y personas adultas de Iberoam\u00e9rica en la escolaridad a trav\u00e9s de los testimonios de los y las deportistas, con la intenci\u00f3n de remarcar la importancia de la educaci\u00f3n como factor de desarrollo de las personas.<\/p>\n<p>El involucramiento de los y las atletas ol\u00edmpicos\/as constituye un vector estrat\u00e9gico para concretar el objetivo del proyecto, considerando que se trata de personas que han dedicado su vida a disciplinas deportivas que requieren perseverancia y esfuerzo, como terminar los estudios.<\/p>\n<p>En la Carta Ol\u00edmpica queda plasmada expl\u00edcitamente la esencia del Olimpismo, el cual es definido como \u201cuna filosof\u00eda de vida, que exalta y combina en un conjunto arm\u00f3nico las cualidades del cuerpo, la voluntad y el esp\u00edritu, asocia deporte con cultura y formaci\u00f3n, creando as\u00ed un estilo de vida basado en la alegr\u00eda del esfuerzo, el valor educativo del buen ejemplo, la responsabilidad social y el respeto por los principios \u00e9ticos fundamentales universales\u201d.<\/p>\n<p><strong>\u00bfEn d\u00f3nde se puede terminar el secundario?<\/strong><\/p>\n<p>\u00bfVos, un amigo, una amiga o un familiar est\u00e1n pensando en volver a estudiar? Para descubrir la oferta educativa nacional para poder hacerlo <a href=\"https:\/\/oei.int\/oficinas\/argentina\/volveraestudiar\/oferta-educativa-como-volver-a-estudiar\" target=\"_blank\" rel=\"noopener\">hac\u00e9 click ac\u00e1.<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.16&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb global_colors_info=\u00bb{}\u00bb global_module=\u00bb407&#8243; theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_code _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb]<pee style=\"text-align:center;\"><!-- [et_pb_line_break_holder] --><a href=\"#\" onclick=\"if(document.referrer){history.back();}else{window.location.href='\/';}\" class=\"et_pb_button\" style=\"padding:15px 20px\"><!-- [et_pb_line_break_holder] -->  Volver<!-- [et_pb_line_break_holder] --><\/a><!-- [et_pb_line_break_holder] --><\/pee>[\/et_pb_code][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La campa\u00f1a \u00abVolver a estudiar\u00bb tiene por objetivo promover la terminalidad de la educaci\u00f3n secundaria entre adolescentes, j\u00f3venes y personas adultas involucrando a la sociedad y a referentes del mundo del deporte.Comprometidos con la educaci\u00f3n en todos sus niveles y modalidades la RIET es parte de la edici\u00f3n de la campa\u00f1a \u201cVolver a Estudiar\u201d 2024, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"2880","footnotes":""},"categories":[29],"tags":[],"class_list":["post-288","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/posts\/288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/comments?post=288"}],"version-history":[{"count":7,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/posts\/288\/revisions"}],"predecessor-version":[{"id":411,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/posts\/288\/revisions\/411"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/media\/289"}],"wp:attachment":[{"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/media?parent=288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/categories?post=288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/riet-edu.org\/2025\/wp-json\/wp\/v2\/tags?post=288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}